{"id":2378,"date":"2013-03-01T16:11:57","date_gmt":"2013-03-01T15:11:57","guid":{"rendered":"https:\/\/filmingincroatia.hr\/movies\/game-of-thrones-season-4\/"},"modified":"2025-03-26T09:23:34","modified_gmt":"2025-03-26T08:23:34","slug":"game-of-thrones-season-4","status":"publish","type":"movie","link":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/","title":{"rendered":"Igra prijestolja, 4. sezona"},"featured_media":5065,"parent":0,"template":"","format":[69],"year":[74],"country":[60],"class_list":["post-2378","movie","type-movie","status-publish","has-post-thumbnail","hentry","format-tv-serije"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Igra prijestolja, 4. sezona - Filming in Croatia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Igra prijestolja, 4. sezona - Filming in Croatia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Filming in Croatia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T08:23:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2013\/03\/got-s04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/\",\"url\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/\",\"name\":\"Igra prijestolja, 4. sezona - Filming in Croatia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filmingincroatia.hr\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/got-s04.jpg\",\"datePublished\":\"2013-03-01T15:11:57+00:00\",\"dateModified\":\"2025-03-26T08:23:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/#breadcrumb\"},\"inLanguage\":\"hr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filmingincroatia.hr\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/got-s04.jpg\",\"contentUrl\":\"https:\\\/\\\/filmingincroatia.hr\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/got-s04.jpg\",\"width\":2048,\"height\":1362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/game-of-thrones-season-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Movies\",\"item\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/movies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Igra prijestolja, 4. sezona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/\",\"name\":\"Filming in Croatia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#organization\",\"name\":\"HAVC\",\"url\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hr\",\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filmingincroatia.hr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FIC-Logo.png\",\"contentUrl\":\"https:\\\/\\\/filmingincroatia.hr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/FIC-Logo.png\",\"width\":729,\"height\":160,\"caption\":\"HAVC\"},\"image\":{\"@id\":\"https:\\\/\\\/filmingincroatia.hr\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Igra prijestolja, 4. sezona - Filming in Croatia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/","og_locale":"hr_HR","og_type":"article","og_title":"Igra prijestolja, 4. sezona - Filming in Croatia","og_url":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/","og_site_name":"Filming in Croatia","article_modified_time":"2025-03-26T08:23:34+00:00","og_image":[{"width":2048,"height":1362,"url":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2013\/03\/got-s04.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/","url":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/","name":"Igra prijestolja, 4. sezona - Filming in Croatia","isPartOf":{"@id":"https:\/\/filmingincroatia.hr\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/#primaryimage"},"image":{"@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/#primaryimage"},"thumbnailUrl":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2013\/03\/got-s04.jpg","datePublished":"2013-03-01T15:11:57+00:00","dateModified":"2025-03-26T08:23:34+00:00","breadcrumb":{"@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/#breadcrumb"},"inLanguage":"hr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/"]}]},{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/#primaryimage","url":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2013\/03\/got-s04.jpg","contentUrl":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2013\/03\/got-s04.jpg","width":2048,"height":1362},{"@type":"BreadcrumbList","@id":"https:\/\/filmingincroatia.hr\/hr\/movies\/game-of-thrones-season-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/filmingincroatia.hr\/hr\/"},{"@type":"ListItem","position":2,"name":"Movies","item":"https:\/\/filmingincroatia.hr\/hr\/movies\/"},{"@type":"ListItem","position":3,"name":"Igra prijestolja, 4. sezona"}]},{"@type":"WebSite","@id":"https:\/\/filmingincroatia.hr\/hr\/#website","url":"https:\/\/filmingincroatia.hr\/hr\/","name":"Filming in Croatia","description":"","publisher":{"@id":"https:\/\/filmingincroatia.hr\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filmingincroatia.hr\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr"},{"@type":"Organization","@id":"https:\/\/filmingincroatia.hr\/hr\/#organization","name":"HAVC","url":"https:\/\/filmingincroatia.hr\/hr\/","logo":{"@type":"ImageObject","inLanguage":"hr","@id":"https:\/\/filmingincroatia.hr\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2020\/11\/FIC-Logo.png","contentUrl":"https:\/\/filmingincroatia.hr\/wp-content\/uploads\/2020\/11\/FIC-Logo.png","width":729,"height":160,"caption":"HAVC"},"image":{"@id":"https:\/\/filmingincroatia.hr\/hr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/movie\/2378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/movie"}],"about":[{"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/types\/movie"}],"version-history":[{"count":0,"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/movie\/2378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/media\/5065"}],"wp:attachment":[{"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/media?parent=2378"}],"wp:term":[{"taxonomy":"year","embeddable":true,"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/year?post=2378"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/format?post=2378"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/filmingincroatia.hr\/hr\/wp-json\/wp\/v2\/country?post=2378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}